{"id":2294,"date":"2020-05-14T11:36:41","date_gmt":"2020-05-14T09:36:41","guid":{"rendered":"https:\/\/test.iridia.cat\/comunicat-de-la-campanya-estatal-pel-tancament-dels-cie-i-la-fi-de-les-deportacions\/"},"modified":"2024-03-21T13:09:06","modified_gmt":"2024-03-21T12:09:06","slug":"comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones","status":"publish","type":"post","link":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/","title":{"rendered":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones"},"content":{"rendered":"<blockquote>\n<h2><strong>#LosCIEsNoSeAbren<\/strong><\/h2>\n<p><a href=\"https:\/\/iridia.cat\/es\/comunicat-de-la-campanya-estatal-pel-tancament-dels-cie-i-la-fi-de-les-deportacions\/captura-de-pantalla-2020-05-14-a-las-11-45-50\/\" rel=\"attachment wp-att-2299\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-2299 size-medium\" src=\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/Captura-de-pantalla-2020-05-14-a-las-11.45.50-300x169.png\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/Captura-de-pantalla-2020-05-14-a-las-11.45.50-300x169.png 300w, https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/Captura-de-pantalla-2020-05-14-a-las-11.45.50-768x433.png 768w, https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/Captura-de-pantalla-2020-05-14-a-las-11.45.50-1024x577.png 1024w, https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/Captura-de-pantalla-2020-05-14-a-las-11.45.50.png 1082w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p><\/blockquote>\n<p><strong>La semana pasada todos los CIE del Estado espa\u00f1ol quedaron vac\u00edos<\/strong> fruto de las protestas de los internos por la ausencia de medidas de seguridad ante el coronavirus y de la presi\u00f3n social ante la imposibilidad de ejecutar deportaciones en el actual contexto de pandemia. Es la primera vez desde su creaci\u00f3n que no hay personas privadas de libertad en ning\u00fan CIE, es el momento de que este cierre sea irreversible. Por ello, <strong>desde la Campa\u00f1a Estatal por el Cierre de los CIE exigimos al Gobierno que ponga fin a su existencia.<\/strong><\/p>\n<p>Cabe destacar que<strong> la gesti\u00f3n del proceso de puesta en libertad de las personas internas en los CIE ha sido demasiado lenta<\/strong>, a pesar de las recomendaciones de la oficina del Defensor del Pueblo o de las Organizaciones Internacionales de Derechos Humanos, que ped\u00edan la puesta en libertad de las personas migrantes privadas de libertad en centros de reclusi\u00f3n enfocados a la deportaci\u00f3n, pues, <strong>al ser imposible llevar a cabo las expulsiones por el cierre de fronteras, el internamiento carec\u00eda de habilitaci\u00f3n legal.<\/strong><\/p>\n<p>Adem\u00e1s, a pesar de que a las pocas semanas de esta pandemia comenzaron a vaciarse el CIE de Barcelona y el de Madrid, tras la protesta que llevaron a cabo los internos que all\u00ed se encontraban, <strong>la puesta en libertad de las personas internas se ha realizado sin garantizar los desplazamientos al lugar de residencia o la derivaci\u00f3n a los recursos de acogida efectivos<\/strong> en buena parte de los casos. La situaci\u00f3n m\u00e1s grave fue mantener abierto el CIE de Algeciras sin sentido para retener a 4 personas, que finalmente fueron puestas en libertad el pasado 6 de mayo Adem\u00e1s, una de ellas denunci\u00f3 haber sufrido agresiones f\u00edsicas por parte de un polic\u00eda el pasado 27 de abril, que se materializaron en varias patadas y un tortazo que le provoc\u00f3 una hemorragia en el o\u00eddo que no ces\u00f3 en toda la noche, raz\u00f3n por la cual tuvo que ir trasladado al hospital a la ma\u00f1ana siguiente.<\/p>\n<p><strong>Los CIE no deber\u00edan haber existido nunca y estamos ante una coyuntura social y pol\u00edtica que perfectamente posibilitar\u00eda que el actual cierre temporal y contextual se convirtiera en un cierre definitivo.<\/strong> Los CIE son espacios de vulneraci\u00f3n de derechos, de impunidad policial y de sufrimiento y est\u00e1n enmarcados en una l\u00f3gica racista y colonial apartada de la dignidad de las personas que, de ninguna manera, queremos que existan en nuestra sociedad.<\/p>\n<p>Al plantearnos la supuesta vuelta a la normalidad, <strong>nos tememos que el dispositivo deportador se active de nuevo sin una gesti\u00f3n apropiada<\/strong> ni en tiempo, ni en forma, y, consecuentemente, sin las garant\u00edas propias de un Estado de Derecho. En este sentido, el Juzgado de Instrucci\u00f3n n\u00ba9 de Murcia, con funciones de control del CIE de Sangonera la Verde, ha emitido un Auto ante una consulta realizada por el Ministerio Fiscal sobre las condiciones que debe ofrecer este Centro si se decidiera su puesta en funcionamiento, observando la ausencia de cualquier protocolo y medios adecuados que permitan hacer frente a la crisis sanitaria actual si se produjeran casos en su interior. Este mismo Auto refiere la posibilidad de utilizar los protocolos establecidos al efecto en los centros penitenciarios para garantizar su posible reapertura, reconociendo lo que venimos denunciando en la Campa\u00f1a Estatal por el Cierre de los CIE desde su creaci\u00f3n: <strong>los CIE son c\u00e1rceles racistas encubiertas bajo el amparo legal del control de la inmigraci\u00f3n irregular. <\/strong><\/p>\n<p>Adem\u00e1s, nos preocupa profundamente que la eventual recuperaci\u00f3n de la normalidad conlleve la detenci\u00f3n de las personas ahora liberadas, cuya orden de expulsi\u00f3n todav\u00eda est\u00e1 vigente. Del mismo modo, aunque los CIE est\u00e1n vac\u00edos, <strong>condenamos firmemente la gesti\u00f3n del Gobierno en nuestra Frontera Sur y expresamos nuestra m\u00e1xima indignaci\u00f3n ante la horrible situaci\u00f3n que se est\u00e1 viviendo en los Centros de Estancia Temporal de Inmigrantes de Ceuta y Melilla, que es absolutamente insostenible.<\/strong> A pesar del hacinamiento en el que se encuentran ambos CETI en pleno contexto de pandemia, el Gobierno ha decidido mantener la realidad de riesgo y de tensi\u00f3n que sufren, en lugar de trasladar a las personas que all\u00ed se encuentran a lugares de acogida dignos en la pen\u00ednsula. Igualmente, ha amenazado con deportar a m\u00e1s de 600 personas de nacionalidad tunecina que se encuentran en Melilla, forzando la situaci\u00f3n a\u00fan m\u00e1s si cabe.<\/p>\n<p>Por todo ello, manifestamos que <strong>el Estado espa\u00f1ol ejecuta un planteamiento racista e insolidario en sus pol\u00edticas migratorias,<\/strong> excusando la crueldad de sus medidas en una presunta imposici\u00f3n de las instituciones europeas. El actual marco legal de la Uni\u00f3n Europea, lejos de lo que se ha venido planteando ante la opini\u00f3n p\u00fablica, permite que no existan los CIE, ya que la denominada Directiva de la Verg\u00fcenza, que regula el marco de deportaciones a nivel europeo, no obliga a los Estados a prever un tiempo de internamiento en centros de detenci\u00f3n.<\/p>\n<p>Es evidente que el racismo institucional, materializado en una Ley de Extranjer\u00eda xen\u00f3foba que deber\u00eda ser derogada, opera a multitud de niveles en nuestro territorio. <strong>Es necesario cambiar el paradigma en las pol\u00edticas migratorias actuales, comenzando por llevar a cabo de forma urgente un proceso de regularizaci\u00f3n de las personas migrantes que no cuentan con autorizaci\u00f3n de residencia en Espa\u00f1a,<\/strong> al mismo tiempo que se dota la sociedad de herramientas que permitan poner a las personas en el centro, abandonando de inmediato las medidas destructivas, en este caso, convirtiendo en permanente el cierre de los CIE.<\/p>\n<p>&nbsp;<\/p>\n<p>Por todo ello, <strong>EXIGIMOS al Gobierno que:<\/strong><\/p>\n<ol>\n<li><strong>Acuerde no reabrir los CIE y tome las medidas legislativas necesarias para que el cierre sea definitivo y permanente.<\/strong><\/li>\n<li><strong>Lleve a cabo un proceso de regularizaci\u00f3n de las personas migrantes que actualmente residen en el Estado espa\u00f1ol.<\/strong><\/li>\n<li><strong>Traslade de forma inmediata a la pen\u00ednsula a las personas que se encuentran en los CETI de Ceuta y Melilla, ofreci\u00e9ndoles recursos de acogida dignos.<\/strong><\/li>\n<\/ol>\n","protected":false},"excerpt":{"rendered":"<p>#LosCIEsNoSeAbren La semana pasada todos los CIE del Estado espa\u00f1ol quedaron vac\u00edos fruto de las protestas de los internos por la ausencia de medidas de seguridad ante el coronavirus y de la presi\u00f3n social ante la imposibilidad de ejecutar deportaciones en el actual contexto de pandemia. Es la primera vez desde su creaci\u00f3n que no [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":2249,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[58,144],"class_list":["post-2294","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones","tag-comunicados-iridia","tag-migracions-es-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones\" \/>\n<meta property=\"og:description\" content=\"#LosCIEsNoSeAbren La semana pasada todos los CIE del Estado espa\u00f1ol quedaron vac\u00edos fruto de las protestas de los internos por la ausencia de medidas de seguridad ante el coronavirus y de la presi\u00f3n social ante la imposibilidad de ejecutar deportaciones en el actual contexto de pandemia. Es la primera vez desde su creaci\u00f3n que no [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\" \/>\n<meta property=\"og:site_name\" content=\"Ir\u00eddia\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-14T09:36:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-21T12:09:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14-1024x684.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"684\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ir\u00eddia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ir\u00eddia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\"},\"author\":{\"name\":\"Ir\u00eddia\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f\"},\"headline\":\"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones\",\"datePublished\":\"2020-05-14T09:36:41+00:00\",\"dateModified\":\"2024-03-21T12:09:06+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\"},\"wordCount\":1058,\"publisher\":{\"@id\":\"https:\/\/test.iridia.cat\/#organization\"},\"image\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg\",\"keywords\":[\"Comunicados\",\"Migraciones\"],\"articleSection\":[\"Publicaciones\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\",\"url\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\",\"name\":\"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones\",\"isPartOf\":{\"@id\":\"https:\/\/test.iridia.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg\",\"datePublished\":\"2020-05-14T09:36:41+00:00\",\"dateModified\":\"2024-03-21T12:09:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage\",\"url\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg\",\"contentUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg\",\"width\":4240,\"height\":2832,\"caption\":\"Foto: S\u00f2nia Calv\u00f3\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/iridia.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.iridia.cat\/#website\",\"url\":\"https:\/\/test.iridia.cat\/\",\"name\":\"Ir\u00eddia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/test.iridia.cat\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.iridia.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test.iridia.cat\/#organization\",\"name\":\"Ir\u00eddia\",\"url\":\"https:\/\/test.iridia.cat\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png\",\"contentUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png\",\"width\":740,\"height\":220,\"caption\":\"Ir\u00eddia\"},\"image\":{\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f\",\"name\":\"Ir\u00eddia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g\",\"caption\":\"Ir\u00eddia\"},\"url\":\"https:\/\/iridia.cat\/es\/author\/iridia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/","og_locale":"es_ES","og_type":"article","og_title":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones","og_description":"#LosCIEsNoSeAbren La semana pasada todos los CIE del Estado espa\u00f1ol quedaron vac\u00edos fruto de las protestas de los internos por la ausencia de medidas de seguridad ante el coronavirus y de la presi\u00f3n social ante la imposibilidad de ejecutar deportaciones en el actual contexto de pandemia. Es la primera vez desde su creaci\u00f3n que no [&hellip;]","og_url":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/","og_site_name":"Ir\u00eddia","article_published_time":"2020-05-14T09:36:41+00:00","article_modified_time":"2024-03-21T12:09:06+00:00","og_image":[{"width":1024,"height":684,"url":"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14-1024x684.jpg","type":"image\/jpeg"}],"author":"Ir\u00eddia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ir\u00eddia","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#article","isPartOf":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/"},"author":{"name":"Ir\u00eddia","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f"},"headline":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones","datePublished":"2020-05-14T09:36:41+00:00","dateModified":"2024-03-21T12:09:06+00:00","mainEntityOfPage":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/"},"wordCount":1058,"publisher":{"@id":"https:\/\/test.iridia.cat\/#organization"},"image":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg","keywords":["Comunicados","Migraciones"],"articleSection":["Publicaciones"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/","url":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/","name":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones","isPartOf":{"@id":"https:\/\/test.iridia.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage"},"image":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage"},"thumbnailUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg","datePublished":"2020-05-14T09:36:41+00:00","dateModified":"2024-03-21T12:09:06+00:00","breadcrumb":{"@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#primaryimage","url":"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg","contentUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2020\/05\/14.jpg","width":4240,"height":2832,"caption":"Foto: S\u00f2nia Calv\u00f3"},{"@type":"BreadcrumbList","@id":"https:\/\/iridia.cat\/es\/comunicado-de-la-campana-estatal-por-cierre-de-los-cie-y-el-fin-de-las-deportaciones\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/iridia.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Comunicado de la Campa\u00f1a Estatal por el cierre de los CIE y el fin de las deportaciones"}]},{"@type":"WebSite","@id":"https:\/\/test.iridia.cat\/#website","url":"https:\/\/test.iridia.cat\/","name":"Ir\u00eddia","description":"","publisher":{"@id":"https:\/\/test.iridia.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.iridia.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/test.iridia.cat\/#organization","name":"Ir\u00eddia","url":"https:\/\/test.iridia.cat\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/","url":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png","contentUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png","width":740,"height":220,"caption":"Ir\u00eddia"},"image":{"@id":"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f","name":"Ir\u00eddia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g","caption":"Ir\u00eddia"},"url":"https:\/\/iridia.cat\/es\/author\/iridia\/"}]}},"_links":{"self":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/2294","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/comments?post=2294"}],"version-history":[{"count":5,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/2294\/revisions"}],"predecessor-version":[{"id":2305,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/2294\/revisions\/2305"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/media\/2249"}],"wp:attachment":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/media?parent=2294"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/categories?post=2294"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/tags?post=2294"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}