{"id":5617,"date":"2022-10-20T09:17:08","date_gmt":"2022-10-20T07:17:08","guid":{"rendered":"https:\/\/test.iridia.cat\/?p=5617"},"modified":"2024-01-24T16:06:34","modified_gmt":"2024-01-24T15:06:34","slug":"lanzamos-la-campana-con-memoria-derechos-humanos","status":"publish","type":"post","link":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/","title":{"rendered":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d"},"content":{"rendered":"<p><strong>Publicamos un espot que pone el acento en la importancia de la memoria colectiva para evitar la impunidad en casos de violencia institucional. Adem\u00e1s, lanzamos una nueva campa\u00f1a de crowdfunding destinada a financiar el Servicio de Atenci\u00f3n y Denuncia.<br \/>\n<\/strong><\/p>\n<p><iframe loading=\"lazy\" title=\"YouTube video player\" src=\"https:\/\/www.youtube.com\/embed\/rVA_V_y7KkU\" width=\"760\" height=\"515\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n<p><strong><a href=\"https:\/\/www.goteo.org\/project\/amb-memoria-drets-humans\">Crowedfunding #ConMemoriaDerechosHumanos<\/a><\/strong><\/p>\n<p>Con este corto queremos poner en valor la importancia de la memoria colectiva, defendiendo que <strong>la memoria puede ser una aliada para mantenernos vivas y fuertes para cambiar lo que no nos gusta.<\/strong> Nuestra historia est\u00e1 llena de discriminaciones, represi\u00f3n, colonialismo, vallas, celdas de comisarias y de prisiones, grises, CIEs, golpes, censura, miedo&#8230; y en definitiva, de personas que han sufrido situaciones de violencia institucional y que merecen verdad, justicia, reparaci\u00f3n y garant\u00edas de no-repetici\u00f3n. Pero tambi\u00e9n de momentos esperanzadores, de mobilizaci\u00f3n, denuncia de injusticias y victorias sociales para recordar que la historia tambi\u00e9n es lo que compartimos, lo que construimos juntas para escoger como queremos vivir.<\/p>\n<p>La campa\u00f1a Con Memoria, Derechos Humanos, tiene como objetivo impulsar un crowdfunding que sirva para financiar el Servicio de Atenci\u00f3n y Denuncia ante casos de violencia institucional, que ya <strong>ha atendido a m\u00e1s de 650 personas desde que se fund\u00f3 en 2016<\/strong>. Actualmente actuamos como acusaci\u00f3n en 56 casos, por los que hay <strong>127 agentes de polic\u00eda, seguridad privada o funcionarios de prisiones investigados.<\/strong> El servicio es gratuito para todas las personas afectadas, y depende en m\u00e1s de un 60% de donaciones privadas y aportaciones de personas socias.<\/p>\n<p>Ana\u00efs Franquesa, co-directora de Ir\u00eddia, explica que &#8220;sin el apoyo de la ciudadan\u00eda ser\u00eda imposible que existiese un servicio gratuito, que adem\u00e1s de dar soporte a personas que lo necesiten <strong>promueve cambios y mejoras sociales&#8221;<\/strong>. Como ejemplo, cita los cambios en la normativa que regula la <strong>identificaci\u00f3n de los agentes antidisturbios<\/strong> de Mossos d&#8217;Esquadra, que ahora tienen que ir identificados por delante, por detr\u00e1s y en el casco; la creaci\u00f3n y participaci\u00f3n de entidades de derechos humanos, expertos y personas afectadas en la Comisi\u00f3n de Estudio del Modelo Policial del Parlament o la presentaci\u00f3n de enmiendas a la<strong> Ley de Memoria<\/strong> catalana.<\/p>\n<p>Para terminar, anunciamos que celebraremos nuestro <strong>7o aniversario<\/strong> con un gran acto el 30 de noviembre en el espacio Calabria 66, en que mezclaremos una vez m\u00e1s <strong>cultura y derechos humanos<\/strong>. Tomar\u00e1 parte del mismo la nueva Junta de Ir\u00eddia, que se estren\u00f3 con la pasada Asamblea de socias en el mes de junio y que cuenta con <strong>Ester Quintana<\/strong> como presidenta, acompa\u00f1ada por <strong>Andreu Van den Eynde, Aina Estarellas, Blanca Garc\u00e9s, Jordi de Senespleda, Jordi Bosch, Carmen Juares<\/strong> y<strong> Irene Santiago<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Publicamos un espot que pone el acento en la importancia de la memoria colectiva para evitar la impunidad en casos de violencia institucional. Adem\u00e1s, lanzamos una nueva campa\u00f1a de crowdfunding destinada a financiar el Servicio de Atenci\u00f3n y Denuncia. Crowedfunding #ConMemoriaDerechosHumanos Con este corto queremos poner en valor la importancia de la memoria colectiva, defendiendo [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":5621,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[3],"tags":[120,124],"class_list":["post-5617","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publicaciones","tag-iridiafest-es","tag-socias"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.0 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d\" \/>\n<meta property=\"og:description\" content=\"Publicamos un espot que pone el acento en la importancia de la memoria colectiva para evitar la impunidad en casos de violencia institucional. Adem\u00e1s, lanzamos una nueva campa\u00f1a de crowdfunding destinada a financiar el Servicio de Atenci\u00f3n y Denuncia. Crowedfunding #ConMemoriaDerechosHumanos Con este corto queremos poner en valor la importancia de la memoria colectiva, defendiendo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\" \/>\n<meta property=\"og:site_name\" content=\"Ir\u00eddia\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-20T07:17:08+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-24T15:06:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1198\" \/>\n\t<meta property=\"og:image:height\" content=\"884\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ir\u00eddia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ir\u00eddia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\"},\"author\":{\"name\":\"Ir\u00eddia\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f\"},\"headline\":\"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d\",\"datePublished\":\"2022-10-20T07:17:08+00:00\",\"dateModified\":\"2024-01-24T15:06:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\"},\"wordCount\":453,\"publisher\":{\"@id\":\"https:\/\/test.iridia.cat\/#organization\"},\"image\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg\",\"keywords\":[\"Ir\u00eddiaFest\",\"Socias\"],\"articleSection\":[\"Publicaciones\"],\"inLanguage\":\"es-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\",\"url\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\",\"name\":\"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d\",\"isPartOf\":{\"@id\":\"https:\/\/test.iridia.cat\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg\",\"datePublished\":\"2022-10-20T07:17:08+00:00\",\"dateModified\":\"2024-01-24T15:06:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#breadcrumb\"},\"inLanguage\":\"es-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage\",\"url\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg\",\"contentUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg\",\"width\":1198,\"height\":884},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/iridia.cat\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/test.iridia.cat\/#website\",\"url\":\"https:\/\/test.iridia.cat\/\",\"name\":\"Ir\u00eddia\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\/\/test.iridia.cat\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/test.iridia.cat\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/test.iridia.cat\/#organization\",\"name\":\"Ir\u00eddia\",\"url\":\"https:\/\/test.iridia.cat\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png\",\"contentUrl\":\"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png\",\"width\":740,\"height\":220,\"caption\":\"Ir\u00eddia\"},\"image\":{\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f\",\"name\":\"Ir\u00eddia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es-ES\",\"@id\":\"https:\/\/test.iridia.cat\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g\",\"caption\":\"Ir\u00eddia\"},\"url\":\"https:\/\/iridia.cat\/es\/author\/iridia\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/","og_locale":"es_ES","og_type":"article","og_title":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d","og_description":"Publicamos un espot que pone el acento en la importancia de la memoria colectiva para evitar la impunidad en casos de violencia institucional. Adem\u00e1s, lanzamos una nueva campa\u00f1a de crowdfunding destinada a financiar el Servicio de Atenci\u00f3n y Denuncia. Crowedfunding #ConMemoriaDerechosHumanos Con este corto queremos poner en valor la importancia de la memoria colectiva, defendiendo [&hellip;]","og_url":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/","og_site_name":"Ir\u00eddia","article_published_time":"2022-10-20T07:17:08+00:00","article_modified_time":"2024-01-24T15:06:34+00:00","og_image":[{"width":1198,"height":884,"url":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg","type":"image\/jpeg"}],"author":"Ir\u00eddia","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Ir\u00eddia","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#article","isPartOf":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/"},"author":{"name":"Ir\u00eddia","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f"},"headline":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d","datePublished":"2022-10-20T07:17:08+00:00","dateModified":"2024-01-24T15:06:34+00:00","mainEntityOfPage":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/"},"wordCount":453,"publisher":{"@id":"https:\/\/test.iridia.cat\/#organization"},"image":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg","keywords":["Ir\u00eddiaFest","Socias"],"articleSection":["Publicaciones"],"inLanguage":"es-ES"},{"@type":"WebPage","@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/","url":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/","name":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d","isPartOf":{"@id":"https:\/\/test.iridia.cat\/#website"},"primaryImageOfPage":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage"},"image":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage"},"thumbnailUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg","datePublished":"2022-10-20T07:17:08+00:00","dateModified":"2024-01-24T15:06:34+00:00","breadcrumb":{"@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#breadcrumb"},"inLanguage":"es-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/"]}]},{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#primaryimage","url":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg","contentUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/photo_5947080982882531395_y.jpg","width":1198,"height":884},{"@type":"BreadcrumbList","@id":"https:\/\/iridia.cat\/es\/lanzamos-la-campana-con-memoria-derechos-humanos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/iridia.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Lanzamos la campa\u00f1a \u201cCon Memoria, Derechos Humanos\u201d"}]},{"@type":"WebSite","@id":"https:\/\/test.iridia.cat\/#website","url":"https:\/\/test.iridia.cat\/","name":"Ir\u00eddia","description":"","publisher":{"@id":"https:\/\/test.iridia.cat\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/test.iridia.cat\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es-ES"},{"@type":"Organization","@id":"https:\/\/test.iridia.cat\/#organization","name":"Ir\u00eddia","url":"https:\/\/test.iridia.cat\/","logo":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/","url":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png","contentUrl":"https:\/\/iridia.cat\/wp-content\/uploads\/2022\/10\/avatar_iridia.png","width":740,"height":220,"caption":"Ir\u00eddia"},"image":{"@id":"https:\/\/test.iridia.cat\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/4cd6357ca92585af3bb3f05b5c669d5f","name":"Ir\u00eddia","image":{"@type":"ImageObject","inLanguage":"es-ES","@id":"https:\/\/test.iridia.cat\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5b7e0123885b2270f0bc833c606fa7b6ae733761d3e80d47e23ba829fe3bd7f7?s=96&d=mm&r=g","caption":"Ir\u00eddia"},"url":"https:\/\/iridia.cat\/es\/author\/iridia\/"}]}},"_links":{"self":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/5617","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/comments?post=5617"}],"version-history":[{"count":2,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/5617\/revisions"}],"predecessor-version":[{"id":5625,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/posts\/5617\/revisions\/5625"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/media\/5621"}],"wp:attachment":[{"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/media?parent=5617"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/categories?post=5617"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/iridia.cat\/es\/wp-json\/wp\/v2\/tags?post=5617"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}